{"id":19147,"date":"2022-01-11T21:52:04","date_gmt":"2022-01-11T21:52:04","guid":{"rendered":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/prodotto\/orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044\/"},"modified":"2025-07-23T17:51:53","modified_gmt":"2025-07-23T17:51:53","slug":"orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044","status":"publish","type":"product","link":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044\/","title":{"rendered":"Orecchini I Classici a monachella con pastiglia tonda piccola"},"content":{"rendered":"<p>Realizzata interamente a mano, questa creazione Aquaforte nasce dalla passione e dall esperienza di maestri orafi artigiani.<\/p>\n<p>In ogni particolare di questo gioiello in argento 925\/000 si riconoscono l&#8217;origine italiana e lo stile internazionale.<\/p>\n<p>La placcatura in oro giallo 23 carati, rivestita da uno speciale trattamento, \u00e8 rigorosamente eseguita senza alcun rilascio di nichel e cadmio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Orecchini pastiglia tonda leggeri, stampati e accoppiati in AG 925\u2030, placcato oro giallo 23 ct e satinati&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:2817,&quot;3&quot;:{&quot;1&quot;:0},&quot;11&quot;:4,&quot;12&quot;:0,&quot;14&quot;:{&quot;1&quot;:3,&quot;3&quot;:1}}\">Orecchini pastiglia tonda leggeri, stampati e accoppiati in AG 925\u2030, placcato oro giallo 23 ct e satinati<\/p>\n<ul>\n<li aria-level=\"1\">argento 925\/000<\/li>\n<li aria-level=\"1\">placcatura in oro giallo 23 carati<\/li>\n<li aria-level=\"1\">rivestimento con speciale trattamento che protegge dalla naturale ossidazione del metallo<\/li>\n<li aria-level=\"1\">orgogliosamente fatto a mano in Italia<\/li>\n<li aria-level=\"1\">placcature rigorosamente senza alcun rilascio di nichel e cadmio<\/li>\n<li aria-level=\"1\">comfort fit<\/li>\n<\/ul>\n","protected":false},"featured_media":19145,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_cat":[633,613,625,615,637],"product_tag":[],"class_list":{"0":"post-19147","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-linee","7":"product_cat-collezioni","8":"product_cat-orecchini","9":"product_cat-gioielli","10":"product_cat-i-classici","12":"first","13":"instock","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Orecchini I Classici a monachella con pastiglia tonda piccola<\/title>\n<meta name=\"description\" content=\"Orecchini pastiglia tonda leggeri, stampati e accoppiati in AG 925\u2030, placcato oro giallo 23 ct e satinati\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Orecchini I Classici a monachella con pastiglia tonda piccola\" \/>\n<meta property=\"og:description\" content=\"Orecchini pastiglia tonda leggeri, stampati e accoppiati in AG 925\u2030, placcato oro giallo 23 ct e satinati\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044\/\" \/>\n<meta property=\"og:site_name\" content=\"Aquaforte Vicenza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AquaforteVicenza\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-23T17:51:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/wp-content\/uploads\/2022\/01\/h0310044-c5c.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044\/\",\"url\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044\/\",\"name\":\"Orecchini I Classici a monachella con pastiglia tonda piccola\",\"isPartOf\":{\"@id\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/wp-content\/uploads\/2022\/01\/h0310044-c5c.jpg\",\"datePublished\":\"2022-01-11T21:52:04+00:00\",\"dateModified\":\"2025-07-23T17:51:53+00:00\",\"description\":\"Orecchini pastiglia tonda leggeri, stampati e accoppiati in AG 925\u2030, placcato oro giallo 23 ct e satinati\",\"breadcrumb\":{\"@id\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044\/#primaryimage\",\"url\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/wp-content\/uploads\/2022\/01\/h0310044-c5c.jpg\",\"contentUrl\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/wp-content\/uploads\/2022\/01\/h0310044-c5c.jpg\",\"width\":900,\"height\":900,\"caption\":\"Orecchini I Classici a monachella con pastiglia tonda piccola-0\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Homepage\",\"item\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Orecchini I Classici a monachella con pastiglia tonda piccola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/#website\",\"url\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/\",\"name\":\"Aquaforte Vicenza\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Orecchini I Classici a monachella con pastiglia tonda piccola","description":"Orecchini pastiglia tonda leggeri, stampati e accoppiati in AG 925\u2030, placcato oro giallo 23 ct e satinati","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044\/","og_locale":"it_IT","og_type":"article","og_title":"Orecchini I Classici a monachella con pastiglia tonda piccola","og_description":"Orecchini pastiglia tonda leggeri, stampati e accoppiati in AG 925\u2030, placcato oro giallo 23 ct e satinati","og_url":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044\/","og_site_name":"Aquaforte Vicenza","article_publisher":"https:\/\/www.facebook.com\/AquaforteVicenza\/","article_modified_time":"2025-07-23T17:51:53+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/wp-content\/uploads\/2022\/01\/h0310044-c5c.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044\/","url":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044\/","name":"Orecchini I Classici a monachella con pastiglia tonda piccola","isPartOf":{"@id":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044\/#primaryimage"},"image":{"@id":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044\/#primaryimage"},"thumbnailUrl":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/wp-content\/uploads\/2022\/01\/h0310044-c5c.jpg","datePublished":"2022-01-11T21:52:04+00:00","dateModified":"2025-07-23T17:51:53+00:00","description":"Orecchini pastiglia tonda leggeri, stampati e accoppiati in AG 925\u2030, placcato oro giallo 23 ct e satinati","breadcrumb":{"@id":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044\/#primaryimage","url":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/wp-content\/uploads\/2022\/01\/h0310044-c5c.jpg","contentUrl":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/wp-content\/uploads\/2022\/01\/h0310044-c5c.jpg","width":900,"height":900,"caption":"Orecchini I Classici a monachella con pastiglia tonda piccola-0"},{"@type":"BreadcrumbList","@id":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/orecchini-i-classici-a-monachella-con-pastiglia-tonda-piccola-h0310044\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/"},{"@type":"ListItem","position":2,"name":"Homepage","item":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/"},{"@type":"ListItem","position":3,"name":"Orecchini I Classici a monachella con pastiglia tonda piccola"}]},{"@type":"WebSite","@id":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/#website","url":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/","name":"Aquaforte Vicenza","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/wp-json\/wp\/v2\/product\/19147"}],"collection":[{"href":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/wp-json\/wp\/v2\/comments?post=19147"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/wp-json\/wp\/v2\/media\/19145"}],"wp:attachment":[{"href":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/wp-json\/wp\/v2\/media?parent=19147"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/wp-json\/wp\/v2\/product_cat?post=19147"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/wp-json\/wp\/v2\/product_tag?post=19147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}