{"id":19095,"date":"2022-01-11T13:51:05","date_gmt":"2022-01-11T13:51:05","guid":{"rendered":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/prodotto\/collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570\/"},"modified":"2025-07-23T17:52:11","modified_gmt":"2025-07-23T17:52:11","slug":"collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570","status":"publish","type":"product","link":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570\/","title":{"rendered":"Collana  Retr\u00f2 con elemento pendente satinato a mano unito alla catena da  un elemento di cubic zirconia bianchi"},"content":{"rendered":"<p>Ogni gioiello \u00e8 accompagnato da una confezione regalo e dalla shopper Aquaforte.<br \/>Realizzata interamente a mano, questa creazione Aquaforte nasce dalla passione e dall esperienza di maestri orafi artigiani.In ogni particolare di questo gioiello in argento 925\/000 si riconoscono l&#8217;origine italiana e lo stile internazionale.La placcatura in oro giallo 23 carati, rivestita da uno speciale trattamento, \u00e8 rigorosamente eseguita senza alcun rilascio di nichel e cadmio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Collana in AG 925\u2030 placcato oro giallo 23 ct, con elemento pendente  satinato a mano e legato alla catena tramite una rondella di cubic zirconia bianchi. Cm 42 + ext&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:6915,&quot;3&quot;:{&quot;1&quot;:0},&quot;4&quot;:{&quot;1&quot;:2,&quot;2&quot;:16777215},&quot;11&quot;:4,&quot;12&quot;:0,&quot;14&quot;:{&quot;1&quot;:2,&quot;2&quot;:0},&quot;15&quot;:&quot;Roboto, RobotoDraft, Helvetica, Arial, sans-serif&quot;}\">Collana in AG 925\u2030 placcato oro giallo 23 ct, con elemento pendente satinato a mano e legato alla catena tramite una rondella di cubic zirconia bianchi. Cm 42 + ext<\/p>\n<ul>\n<li aria-level=\"1\">argento 925\/000<\/li>\n<li aria-level=\"1\">placcatura in oro giallo 23 carati<\/li>\n<li aria-level=\"1\">rivestimento con speciale trattamento che protegge dalla naturale ossidazione del metallo<\/li>\n<li aria-level=\"1\">orgogliosamente fatto a mano in Italia<\/li>\n<li aria-level=\"1\">placcature rigorosamente senza alcun rilascio di nichel e cadmio<\/li>\n<li aria-level=\"1\">comfort fit<\/li>\n<\/ul>\n","protected":false},"featured_media":19091,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_cat":[633,613,615,629,649],"product_tag":[],"class_list":{"0":"post-19095","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-linee","7":"product_cat-collezioni","8":"product_cat-gioielli","9":"product_cat-collane","10":"product_cat-retro","12":"first","13":"instock","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Collana Retr\u00f2 con elemento pendente satinato a mano unito alla catena da un elemento di cubic zirconia bianchi<\/title>\n<meta name=\"description\" content=\"Collana in AG 925\u2030 placcato oro giallo 23 ct, con elemento pendente satinato a mano e legato alla catena tramite una rondella di cubic zirconia bianchi. Cm 42 + ext\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Collana Retr\u00f2 con elemento pendente satinato a mano unito alla catena da un elemento di cubic zirconia bianchi\" \/>\n<meta property=\"og:description\" content=\"Collana in AG 925\u2030 placcato oro giallo 23 ct, con elemento pendente satinato a mano e legato alla catena tramite una rondella di cubic zirconia bianchi. Cm 42 + ext\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570\/\" \/>\n<meta property=\"og:site_name\" content=\"Aquaforte Vicenza\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AquaforteVicenza\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-23T17:52:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/wp-content\/uploads\/2022\/01\/h0464570-e61.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570\/\",\"url\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570\/\",\"name\":\"Collana Retr\u00f2 con elemento pendente satinato a mano unito alla catena da un elemento di cubic zirconia bianchi\",\"isPartOf\":{\"@id\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/wp-content\/uploads\/2022\/01\/h0464570-e61.jpg\",\"datePublished\":\"2022-01-11T13:51:05+00:00\",\"dateModified\":\"2025-07-23T17:52:11+00:00\",\"description\":\"Collana in AG 925\u2030 placcato oro giallo 23 ct, con elemento pendente satinato a mano e legato alla catena tramite una rondella di cubic zirconia bianchi. Cm 42 + ext\",\"breadcrumb\":{\"@id\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570\/#primaryimage\",\"url\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/wp-content\/uploads\/2022\/01\/h0464570-e61.jpg\",\"contentUrl\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/wp-content\/uploads\/2022\/01\/h0464570-e61.jpg\",\"width\":900,\"height\":900,\"caption\":\"Collana Retr\u00f2 con elemento pendente satinato a mano unito alla catena da un elemento di cubic zirconia bianchi-0\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Homepage\",\"item\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Collana Retr\u00f2 con elemento pendente satinato a mano unito alla catena da un elemento di cubic zirconia bianchi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/#website\",\"url\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/\",\"name\":\"Aquaforte Vicenza\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Collana Retr\u00f2 con elemento pendente satinato a mano unito alla catena da un elemento di cubic zirconia bianchi","description":"Collana in AG 925\u2030 placcato oro giallo 23 ct, con elemento pendente satinato a mano e legato alla catena tramite una rondella di cubic zirconia bianchi. Cm 42 + ext","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570\/","og_locale":"it_IT","og_type":"article","og_title":"Collana Retr\u00f2 con elemento pendente satinato a mano unito alla catena da un elemento di cubic zirconia bianchi","og_description":"Collana in AG 925\u2030 placcato oro giallo 23 ct, con elemento pendente satinato a mano e legato alla catena tramite una rondella di cubic zirconia bianchi. Cm 42 + ext","og_url":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570\/","og_site_name":"Aquaforte Vicenza","article_publisher":"https:\/\/www.facebook.com\/AquaforteVicenza\/","article_modified_time":"2025-07-23T17:52:11+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/wp-content\/uploads\/2022\/01\/h0464570-e61.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570\/","url":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570\/","name":"Collana Retr\u00f2 con elemento pendente satinato a mano unito alla catena da un elemento di cubic zirconia bianchi","isPartOf":{"@id":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570\/#primaryimage"},"image":{"@id":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570\/#primaryimage"},"thumbnailUrl":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/wp-content\/uploads\/2022\/01\/h0464570-e61.jpg","datePublished":"2022-01-11T13:51:05+00:00","dateModified":"2025-07-23T17:52:11+00:00","description":"Collana in AG 925\u2030 placcato oro giallo 23 ct, con elemento pendente satinato a mano e legato alla catena tramite una rondella di cubic zirconia bianchi. Cm 42 + ext","breadcrumb":{"@id":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570\/#primaryimage","url":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/wp-content\/uploads\/2022\/01\/h0464570-e61.jpg","contentUrl":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/wp-content\/uploads\/2022\/01\/h0464570-e61.jpg","width":900,"height":900,"caption":"Collana Retr\u00f2 con elemento pendente satinato a mano unito alla catena da un elemento di cubic zirconia bianchi-0"},{"@type":"BreadcrumbList","@id":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/prodotto\/collana-retro-con-elemento-pendente-satinato-a-mano-unito-alla-catena-da-un-elemento-di-cubic-zirconia-bianchi-h0464570\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/"},{"@type":"ListItem","position":2,"name":"Homepage","item":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/"},{"@type":"ListItem","position":3,"name":"Collana Retr\u00f2 con elemento pendente satinato a mano unito alla catena da un elemento di cubic zirconia bianchi"}]},{"@type":"WebSite","@id":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/#website","url":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/","name":"Aquaforte Vicenza","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/wp-json\/wp\/v2\/product\/19095"}],"collection":[{"href":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/wp-json\/wp\/v2\/comments?post=19095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/wp-json\/wp\/v2\/media\/19091"}],"wp:attachment":[{"href":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/wp-json\/wp\/v2\/media?parent=19095"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/wp-json\/wp\/v2\/product_cat?post=19095"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/aquafortevicenza.it-staging.developlab.biz\/it\/wp-json\/wp\/v2\/product_tag?post=19095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}